{"id":823576,"date":"2016-02-04T15:40:38","date_gmt":"2016-02-04T14:40:38","guid":{"rendered":"https:\/\/exindex.hu\/?p=823576"},"modified":"2016-02-20T02:08:15","modified_gmt":"2016-02-20T01:08:15","slug":"ami-marad-soha-nem-ter-vissza","status":"publish","type":"post","link":"https:\/\/exindex.hu\/hu\/hirek\/ami-marad-soha-nem-ter-vissza\/","title":{"rendered":"Ami marad, soha nem t\u00e9r vissza"},"content":{"rendered":"<p><strong>Schikowski Alexander ki\u00e1ll\u00edt\u00e1sa<\/strong><\/p>\r\n\r\n<p>Lak\u00e1sgal\u00e9ria<br \/>\r\n Budapest, XIII.ker\u00fclet, Holl\u00e1n Ern\u0151 utca 46. II. em. 1. kapucseng\u0151 21<\/p>\r\n\r\n<p>Megnyitja Aknai Katalin, m\u0171v\u00e9szett\u00f6rt\u00e9n\u00e9sz <strong>2016. Febru\u00e1r 9.-\u00e9n, kedden 18 \u00f3ra<\/strong>kor<\/p>\r\n\r\n<p>Megtekinthet\u0151 febru\u00e1r 15-\u00e9n h\u00e9tf\u0151n, febru\u00e1r 16-\u00e1n kedden \u00e9s febru\u00e1r  17-\u00e9n szerd\u00e1n, d\u00e9lut\u00e1n 16 &#8211; 18 \u00f3ra k\u00f6z\u00f6tt. A nyitvatart\u00e1si id\u0151n k\u00edv\u00fcl az  alexschiko@web.de-n lehet id\u0151pontot egyeztetni.<\/p>\r\n\r\n\r\n<div><a href=\"\/wp-content\/uploads\/x\/schikowski.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-3577\" src=\"\/wp-content\/uploads\/x\/schikowski-450x331.jpg\" alt=\"\" width=\"450\" height=\"331\" \/><\/a><\/div>\r\n<div><\/div>\r\n<div><a href=\"http:\/\/www.videbimus.de\" target=\"_blank\">videbimus.de<\/a><\/div>\r\n<div><a href=\"http:\/\/www.redstargate.net\" target=\"_blank\">redstargate.net<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Schikowski Alexander ki\u00e1ll\u00edt\u00e1sa Lak\u00e1sgal\u00e9ria Budapest, XIII.ker\u00fclet, Holl\u00e1n Ern\u0151 utca 46. II. em. 1. kapucseng\u0151 21 Megnyitja Aknai Katalin, m\u0171v\u00e9szett\u00f6rt\u00e9n\u00e9sz 2016. Febru\u00e1r 9.-\u00e9n, kedden 18 \u00f3rakor Megtekinthet\u0151 febru\u00e1r 15-\u00e9n h\u00e9tf\u0151n, febru\u00e1r 16-\u00e1n kedden \u00e9s febru\u00e1r 17-\u00e9n szerd\u00e1n, d\u00e9lut\u00e1n 16 &#8211; 18 \u00f3ra k\u00f6z\u00f6tt. A nyitvatart\u00e1si id\u0151n k\u00edv\u00fcl az alexschiko@web.de-n lehet id\u0151pontot egyeztetni. videbimus.de redstargate.net<\/p>\n","protected":false},"author":1,"featured_media":823577,"parent":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-823576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hirek"],"acf":[],"_links":{"self":[{"href":"https:\/\/exindex.hu\/hu\/wp-json\/wp\/v2\/posts\/823576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exindex.hu\/hu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exindex.hu\/hu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exindex.hu\/hu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exindex.hu\/hu\/wp-json\/wp\/v2\/comments?post=823576"}],"version-history":[{"count":0,"href":"https:\/\/exindex.hu\/hu\/wp-json\/wp\/v2\/posts\/823576\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exindex.hu\/hu\/wp-json\/wp\/v2\/media\/823577"}],"wp:attachment":[{"href":"https:\/\/exindex.hu\/hu\/wp-json\/wp\/v2\/media?parent=823576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exindex.hu\/hu\/wp-json\/wp\/v2\/categories?post=823576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exindex.hu\/hu\/wp-json\/wp\/v2\/tags?post=823576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}